{"id":34,"date":"2024-06-24T14:40:12","date_gmt":"2024-06-24T12:40:12","guid":{"rendered":"https:\/\/www.demilorfilms.com\/index.php\/contact-type-a\/"},"modified":"2026-06-19T00:07:12","modified_gmt":"2026-06-18T22:07:12","slug":"contact-demilorfilms","status":"publish","type":"page","link":"https:\/\/www.demilorfilms.com\/index.php\/contact-demilorfilms\/","title":{"rendered":"Contact"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-34","page","type-page","status-publish"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Contact - VID\u00c9ASTE MARIAGE BIARRITZ | VID\u00c9O MARIAGE BIARRITZ &amp; PAYS BASQUE &amp; LANDES - vid\u00e9aste mariage - France - Mariage Pays Basque - Landes<\/title>\n<meta name=\"description\" content=\"J&#039;ai h\u00e2te de d\u00e9couvrir votre histoire, votre amour et j&#039;esp\u00e8re que nous pourrons r\u00e9aliser ensemble votre film de Mariage. Let&#039;s Go !\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.demilorfilms.com\/index.php\/contact-demilorfilms\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Contact - VID\u00c9ASTE MARIAGE BIARRITZ | VID\u00c9O MARIAGE BIARRITZ &amp; PAYS BASQUE &amp; LANDES - vid\u00e9aste mariage - France - Mariage Pays Basque - Landes\" \/>\n<meta property=\"og:description\" content=\"J&#039;ai h\u00e2te de d\u00e9couvrir votre histoire, votre amour et j&#039;esp\u00e8re que nous pourrons r\u00e9aliser ensemble votre film de Mariage. Let&#039;s Go !\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.demilorfilms.com\/index.php\/contact-demilorfilms\/\" \/>\n<meta property=\"og:site_name\" content=\"VID\u00c9ASTE MARIAGE BIARRITZ | VID\u00c9O MARIAGE BIARRITZ &amp; PAYS BASQUE &amp; LANDES\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-18T22:07:12+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.demilorfilms.com\\\/index.php\\\/contact-demilorfilms\\\/\",\"url\":\"https:\\\/\\\/www.demilorfilms.com\\\/index.php\\\/contact-demilorfilms\\\/\",\"name\":\"Contact - VID\u00c9ASTE MARIAGE BIARRITZ | VID\u00c9O MARIAGE BIARRITZ &amp; PAYS BASQUE &amp; LANDES - vid\u00e9aste mariage - France - Mariage Pays Basque - Landes\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.demilorfilms.com\\\/#website\"},\"datePublished\":\"2024-06-24T12:40:12+00:00\",\"dateModified\":\"2026-06-18T22:07:12+00:00\",\"description\":\"J'ai h\u00e2te de d\u00e9couvrir votre histoire, votre amour et j'esp\u00e8re que nous pourrons r\u00e9aliser ensemble votre film de Mariage. Let's Go !\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.demilorfilms.com\\\/index.php\\\/contact-demilorfilms\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.demilorfilms.com\\\/index.php\\\/contact-demilorfilms\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.demilorfilms.com\\\/index.php\\\/contact-demilorfilms\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.demilorfilms.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Contact\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.demilorfilms.com\\\/#website\",\"url\":\"https:\\\/\\\/www.demilorfilms.com\\\/\",\"name\":\"Demilor Films\",\"description\":\"Demilor Films est bas\u00e9 \u00e0 Biarritz et r\u00e9alise des films de mariages. Je suis Yannick vid\u00e9aste de mariage et je parcours le Pays Basque, la Dordogne, les Landes ainsi que le reste de la France et du monde pour capturer la beaut\u00e9 de votre mariage. Chaque mariage est une nouvelle fa\u00e7on de c\u00e9l\u00e9brer l&#039;amour et j&#039;ai h\u00e2te de d\u00e9couvrir la v\u00f4tre.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.demilorfilms.com\\\/#\\\/schema\\\/person\\\/f1760fb865a1bbe34588e467b9cad000\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.demilorfilms.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/www.demilorfilms.com\\\/#\\\/schema\\\/person\\\/f1760fb865a1bbe34588e467b9cad000\",\"name\":\"admin4559\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.demilorfilms.com\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/LOGO-DE55MILOR-V2-1.png\",\"url\":\"https:\\\/\\\/www.demilorfilms.com\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/LOGO-DE55MILOR-V2-1.png\",\"contentUrl\":\"https:\\\/\\\/www.demilorfilms.com\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/LOGO-DE55MILOR-V2-1.png\",\"width\":1525,\"height\":514,\"caption\":\"admin4559\"},\"logo\":{\"@id\":\"https:\\\/\\\/www.demilorfilms.com\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/LOGO-DE55MILOR-V2-1.png\"},\"sameAs\":[\"http:\\\/\\\/www.demilorfilms.com\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Contact - VID\u00c9ASTE MARIAGE BIARRITZ | VID\u00c9O MARIAGE BIARRITZ &amp; PAYS BASQUE &amp; LANDES - vid\u00e9aste mariage - France - Mariage Pays Basque - Landes","description":"J'ai h\u00e2te de d\u00e9couvrir votre histoire, votre amour et j'esp\u00e8re que nous pourrons r\u00e9aliser ensemble votre film de Mariage. Let's Go !","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.demilorfilms.com\/index.php\/contact-demilorfilms\/","og_locale":"fr_FR","og_type":"article","og_title":"Contact - VID\u00c9ASTE MARIAGE BIARRITZ | VID\u00c9O MARIAGE BIARRITZ &amp; PAYS BASQUE &amp; LANDES - vid\u00e9aste mariage - France - Mariage Pays Basque - Landes","og_description":"J'ai h\u00e2te de d\u00e9couvrir votre histoire, votre amour et j'esp\u00e8re que nous pourrons r\u00e9aliser ensemble votre film de Mariage. Let's Go !","og_url":"https:\/\/www.demilorfilms.com\/index.php\/contact-demilorfilms\/","og_site_name":"VID\u00c9ASTE MARIAGE BIARRITZ | VID\u00c9O MARIAGE BIARRITZ &amp; PAYS BASQUE &amp; LANDES","article_modified_time":"2026-06-18T22:07:12+00:00","twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.demilorfilms.com\/index.php\/contact-demilorfilms\/","url":"https:\/\/www.demilorfilms.com\/index.php\/contact-demilorfilms\/","name":"Contact - VID\u00c9ASTE MARIAGE BIARRITZ | VID\u00c9O MARIAGE BIARRITZ &amp; PAYS BASQUE &amp; LANDES - vid\u00e9aste mariage - France - Mariage Pays Basque - Landes","isPartOf":{"@id":"https:\/\/www.demilorfilms.com\/#website"},"datePublished":"2024-06-24T12:40:12+00:00","dateModified":"2026-06-18T22:07:12+00:00","description":"J'ai h\u00e2te de d\u00e9couvrir votre histoire, votre amour et j'esp\u00e8re que nous pourrons r\u00e9aliser ensemble votre film de Mariage. Let's Go !","breadcrumb":{"@id":"https:\/\/www.demilorfilms.com\/index.php\/contact-demilorfilms\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.demilorfilms.com\/index.php\/contact-demilorfilms\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.demilorfilms.com\/index.php\/contact-demilorfilms\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.demilorfilms.com\/"},{"@type":"ListItem","position":2,"name":"Contact"}]},{"@type":"WebSite","@id":"https:\/\/www.demilorfilms.com\/#website","url":"https:\/\/www.demilorfilms.com\/","name":"Demilor Films","description":"Demilor Films est bas\u00e9 \u00e0 Biarritz et r\u00e9alise des films de mariages. Je suis Yannick vid\u00e9aste de mariage et je parcours le Pays Basque, la Dordogne, les Landes ainsi que le reste de la France et du monde pour capturer la beaut\u00e9 de votre mariage. Chaque mariage est une nouvelle fa\u00e7on de c\u00e9l\u00e9brer l&#039;amour et j&#039;ai h\u00e2te de d\u00e9couvrir la v\u00f4tre.","publisher":{"@id":"https:\/\/www.demilorfilms.com\/#\/schema\/person\/f1760fb865a1bbe34588e467b9cad000"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.demilorfilms.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":["Person","Organization"],"@id":"https:\/\/www.demilorfilms.com\/#\/schema\/person\/f1760fb865a1bbe34588e467b9cad000","name":"admin4559","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.demilorfilms.com\/wp-content\/uploads\/2024\/08\/LOGO-DE55MILOR-V2-1.png","url":"https:\/\/www.demilorfilms.com\/wp-content\/uploads\/2024\/08\/LOGO-DE55MILOR-V2-1.png","contentUrl":"https:\/\/www.demilorfilms.com\/wp-content\/uploads\/2024\/08\/LOGO-DE55MILOR-V2-1.png","width":1525,"height":514,"caption":"admin4559"},"logo":{"@id":"https:\/\/www.demilorfilms.com\/wp-content\/uploads\/2024\/08\/LOGO-DE55MILOR-V2-1.png"},"sameAs":["http:\/\/www.demilorfilms.com"]}]}},"_links":{"self":[{"href":"https:\/\/www.demilorfilms.com\/index.php\/wp-json\/wp\/v2\/pages\/34","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.demilorfilms.com\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.demilorfilms.com\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.demilorfilms.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.demilorfilms.com\/index.php\/wp-json\/wp\/v2\/comments?post=34"}],"version-history":[{"count":62,"href":"https:\/\/www.demilorfilms.com\/index.php\/wp-json\/wp\/v2\/pages\/34\/revisions"}],"predecessor-version":[{"id":1405,"href":"https:\/\/www.demilorfilms.com\/index.php\/wp-json\/wp\/v2\/pages\/34\/revisions\/1405"}],"wp:attachment":[{"href":"https:\/\/www.demilorfilms.com\/index.php\/wp-json\/wp\/v2\/media?parent=34"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}